{"id":5791,"date":"2022-11-18T02:09:50","date_gmt":"2022-11-18T02:09:50","guid":{"rendered":"https:\/\/protysec.com\/wordpresslpj\/?p=5791"},"modified":"2022-11-18T18:04:00","modified_gmt":"2022-11-18T18:04:00","slug":"sabes-que-es-un-simulacro","status":"publish","type":"post","link":"https:\/\/protysec.com\/wordpresslpj\/2022\/11\/18\/sabes-que-es-un-simulacro\/","title":{"rendered":"\u00bfSabes qu\u00e9 es un simulacro?"},"content":{"rendered":"\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:17% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"211\" height=\"239\" src=\"https:\/\/protysec.com\/wordpresslpj\/wp-content\/uploads\/2022\/11\/descarga-2.jpg\" alt=\"\" class=\"wp-image-5812 size-full\" srcset=\"https:\/\/protysec.com\/wordpresslpj\/wp-content\/uploads\/2022\/11\/descarga-2.jpg 211w, https:\/\/protysec.com\/wordpresslpj\/wp-content\/uploads\/2022\/11\/descarga-2-177x200.jpg 177w\" sizes=\"auto, (max-width: 211px) 100vw, 211px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-dark-gray-color has-text-color\"><strong>Los<\/strong> <strong>simulacros son ensayos que permiten identificar que hacer y como actuar en caso de una emergencia, al simular escenarios reales.<\/strong><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:26% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"277\" src=\"https:\/\/protysec.com\/wordpresslpj\/wp-content\/uploads\/2022\/11\/evacuaimages-2-5.jpg\" alt=\"\" class=\"wp-image-5815 size-full\" srcset=\"https:\/\/protysec.com\/wordpresslpj\/wp-content\/uploads\/2022\/11\/evacuaimages-2-5.jpg 169w, https:\/\/protysec.com\/wordpresslpj\/wp-content\/uploads\/2022\/11\/evacuaimages-2-5-122x200.jpg 122w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-dark-gray-color has-text-color\"><strong>1.<\/strong>&#8211;<strong>Permiten comprobar con anticipaci\u00f3n si las acciones que hemos preparado son eficientes.<\/strong><\/p>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:47% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"244\" height=\"207\" src=\"https:\/\/protysec.com\/wordpresslpj\/wp-content\/uploads\/2022\/11\/images-2-1.jpg\" alt=\"\" class=\"wp-image-5816 size-full\" srcset=\"https:\/\/protysec.com\/wordpresslpj\/wp-content\/uploads\/2022\/11\/images-2-1.jpg 244w, https:\/\/protysec.com\/wordpresslpj\/wp-content\/uploads\/2022\/11\/images-2-1-200x170.jpg 200w\" sizes=\"auto, (max-width: 244px) 100vw, 244px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p><strong>2. Mejoran los planes para actuar ante una emergencia o desastre.<\/strong><\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"460\" src=\"https:\/\/protysec.com\/wordpresslpj\/wp-content\/uploads\/2022\/11\/WEB-simulacro-de-evacuacion-2019-28-2.png\" alt=\"\" class=\"wp-image-5819 size-full\" srcset=\"https:\/\/protysec.com\/wordpresslpj\/wp-content\/uploads\/2022\/11\/WEB-simulacro-de-evacuacion-2019-28-2.png 474w, https:\/\/protysec.com\/wordpresslpj\/wp-content\/uploads\/2022\/11\/WEB-simulacro-de-evacuacion-2019-28-2-300x291.png 300w, https:\/\/protysec.com\/wordpresslpj\/wp-content\/uploads\/2022\/11\/WEB-simulacro-de-evacuacion-2019-28-2-200x194.png 200w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p><strong>3. Fomentan la cultura de la protecci\u00f3n civil entre los miembros de nuestra familia y comunidad.<\/strong><\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los simulacros son ensayos que permiten identificar que hacer y como actuar en caso de una emergencia, al simular escenarios reales. 1.&#8211;Permiten comprobar con anticipaci\u00f3n si las acciones que hemos preparado son eficientes. 2. Mejoran los planes para actuar ante una emergencia o desastre. 3. Fomentan la cultura de la protecci\u00f3n civil entre los miembros de nuestra familia y comunidad.<\/p>\n","protected":false},"author":1,"featured_media":5799,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23,24],"tags":[],"class_list":["post-5791","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguritips","category-simulacros"],"_links":{"self":[{"href":"https:\/\/protysec.com\/wordpresslpj\/wp-json\/wp\/v2\/posts\/5791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/protysec.com\/wordpresslpj\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/protysec.com\/wordpresslpj\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/protysec.com\/wordpresslpj\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/protysec.com\/wordpresslpj\/wp-json\/wp\/v2\/comments?post=5791"}],"version-history":[{"count":4,"href":"https:\/\/protysec.com\/wordpresslpj\/wp-json\/wp\/v2\/posts\/5791\/revisions"}],"predecessor-version":[{"id":5820,"href":"https:\/\/protysec.com\/wordpresslpj\/wp-json\/wp\/v2\/posts\/5791\/revisions\/5820"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/protysec.com\/wordpresslpj\/wp-json\/wp\/v2\/media\/5799"}],"wp:attachment":[{"href":"https:\/\/protysec.com\/wordpresslpj\/wp-json\/wp\/v2\/media?parent=5791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/protysec.com\/wordpresslpj\/wp-json\/wp\/v2\/categories?post=5791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/protysec.com\/wordpresslpj\/wp-json\/wp\/v2\/tags?post=5791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}