{"id":5765,"date":"2022-11-13T22:38:43","date_gmt":"2022-11-13T22:38:43","guid":{"rendered":"https:\/\/protysec.com\/wordpresslpj\/?p=5765"},"modified":"2022-11-18T17:58:30","modified_gmt":"2022-11-18T17:58:30","slug":"cuentas-con-el-extintor-de-incendios-adecuado","status":"publish","type":"post","link":"https:\/\/protysec.com\/wordpresslpj\/2022\/11\/13\/cuentas-con-el-extintor-de-incendios-adecuado\/","title":{"rendered":"\u00bfCuentas con el extintor de incendios adecuado?"},"content":{"rendered":"\n<p>Un<strong>&nbsp;<\/strong>extintor<strong>&nbsp;<\/strong>es un elemento port\u00e1til destinado a la lucha contra fuegos incipientes, o principios de incendios, los cuales pueden ser dominados y extinguidos de forma breve en una primera intervenci\u00f3n. Los extintores son una herramienta ideal para poder combatir un fuego en su inicio, con ellos podemos evitar que un fuego se propague y se transforme en un&nbsp;incendio.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/protysec.com\/wordpresslpj\/wp-content\/uploads\/2022\/11\/estintores-5t-2.png\" alt=\"\" class=\"wp-image-5773\" width=\"764\" height=\"634\" srcset=\"https:\/\/protysec.com\/wordpresslpj\/wp-content\/uploads\/2022\/11\/estintores-5t-2.png 1019w, https:\/\/protysec.com\/wordpresslpj\/wp-content\/uploads\/2022\/11\/estintores-5t-2-300x249.png 300w, https:\/\/protysec.com\/wordpresslpj\/wp-content\/uploads\/2022\/11\/estintores-5t-2-768x637.png 768w, https:\/\/protysec.com\/wordpresslpj\/wp-content\/uploads\/2022\/11\/estintores-5t-2-200x166.png 200w\" sizes=\"auto, (max-width: 764px) 100vw, 764px\" \/><\/figure>\n<\/div>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un&nbsp;extintor&nbsp;es un elemento port\u00e1til destinado a la lucha contra fuegos incipientes, o principios de incendios, los cuales pueden ser dominados y extinguidos de forma breve en una primera intervenci\u00f3n. Los extintores son una herramienta ideal para poder combatir un fuego en su inicio, con ellos podemos evitar que un fuego se propague y se transforme en un&nbsp;incendio.<\/p>\n","protected":false},"author":1,"featured_media":5775,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,23],"tags":[],"class_list":["post-5765","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-equipo-contra-incendio","category-seguritips"],"_links":{"self":[{"href":"https:\/\/protysec.com\/wordpresslpj\/wp-json\/wp\/v2\/posts\/5765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/protysec.com\/wordpresslpj\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/protysec.com\/wordpresslpj\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/protysec.com\/wordpresslpj\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/protysec.com\/wordpresslpj\/wp-json\/wp\/v2\/comments?post=5765"}],"version-history":[{"count":5,"href":"https:\/\/protysec.com\/wordpresslpj\/wp-json\/wp\/v2\/posts\/5765\/revisions"}],"predecessor-version":[{"id":5802,"href":"https:\/\/protysec.com\/wordpresslpj\/wp-json\/wp\/v2\/posts\/5765\/revisions\/5802"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/protysec.com\/wordpresslpj\/wp-json\/wp\/v2\/media\/5775"}],"wp:attachment":[{"href":"https:\/\/protysec.com\/wordpresslpj\/wp-json\/wp\/v2\/media?parent=5765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/protysec.com\/wordpresslpj\/wp-json\/wp\/v2\/categories?post=5765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/protysec.com\/wordpresslpj\/wp-json\/wp\/v2\/tags?post=5765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}